{"id":232585,"date":"2022-03-11T07:36:01","date_gmt":"2022-03-11T07:36:01","guid":{"rendered":"https:\/\/www.myswissbionic.com\/?page_id=232585"},"modified":"2025-03-05T08:40:28","modified_gmt":"2025-03-05T08:40:28","slug":"cemp","status":"publish","type":"page","link":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/cemp\/","title":{"rendered":"CEMP"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; module_class=\u00a0\u00bbdh-valign-center-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_color_gradient_start=\u00a0\u00bb#ffffff\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#e5e5e5&Prime; background_image=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/pemf_01.jpg\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb min_height=\u00a0\u00bb90vh\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb45px\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb29px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset1&Prime; header_text_shadow_vertical_length=\u00a0\u00bb0em\u00a0\u00bb header_text_shadow_color=\u00a0\u00bb#000000&Prime; header_2_text_shadow_style=\u00a0\u00bbpreset1&Prime; header_2_text_shadow_vertical_length=\u00a0\u00bb0em\u00a0\u00bb header_2_text_shadow_color=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>CEMP<\/h1>\n<h2>champs \u00e9lectromagn\u00e9tiques puls\u00e9s<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Un champ \u00e9lectromagn\u00e9tique (\u00e9galement appel\u00e9 CEM ou champ EM) est une quantit\u00e9 physique produite par des objets charg\u00e9s \u00e9lectriquement. Les quatre param\u00e8tres cruciaux d\u00e9finissant la structure du signal expos\u00e9 sont les suivants :<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbForme d\u2019onde\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf83e;||fa||900&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbIntensit\u00e9 du champ\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe0e3;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb250ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbFr\u00e9quence\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf773;||fa||900&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb500ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbR\u00e9sonance\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe0f5;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb750ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>En th\u00e9orie, ces 4 composants doivent \u00eatre soigneusement dispos\u00e9s en \u00e9quilibre mutuel (coh\u00e9rence) et introduits dans le corps afin de produire un effet optimal sur la sant\u00e9, tout en \u00e9vitant les effets n\u00e9gatifs. La composition expos\u00e9e des param\u00e8tres de base permet de d\u00e9terminer si un signal \u00e9lectromagn\u00e9tique est nocif (par exemple, celui des syst\u00e8mes informatiques, des t\u00e9l\u00e9phones portables, du WIFI, du Bluetooth, des micro-ondes, des lignes \u00e9lectriques, etc.) ou s\u203ail est b\u00e9n\u00e9fique pour la sant\u00e9 (par exemple, les champs \u00e9lectromagn\u00e9tiques  puls\u00e9s  \u00e0  basse  fr\u00e9quence  (CEMP) utilis\u00e9s dans le domaine des soins de sant\u00e9, pour la prophylaxie et le bien-\u00eatre g\u00e9n\u00e9ral).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbwaveform\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Forme d\u2019onde<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; header_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Une onde est une perturbation qui se d\u00e9place dans l\u2019espace, transf\u00e9rant de l\u2019\u00e9nergie d\u2019un point \u00e0 un autre.  Ceux  d\u2019entre  nous  qui  ont  \u00e9tudi\u00e9  la  physique  ou  l\u2019alg\u00e8bre  sont  familiers avec la repr\u00e9sentation graphique des ondes sinuso\u00efdales. Math\u00e9matiquement, les ondes sinuso\u00efdales peuvent \u00eatre dessin\u00e9es sur un syst\u00e8me de coordonn\u00e9es compos\u00e9 des axes \u00abx\u00bb et \u00aby\u00bb. L\u2019axe des y contient des valeurs positives et n\u00e9gatives. Une onde sinuso\u00efdale varie de mani\u00e8re cyclique au-dessus et au-dessous de l\u2019axe des y, et est sym\u00e9trique par rapport \u00e0 l\u2019axe des z\u00e9ros (ou axe des x). La valeur la plus positive se trouve au \u00abpic\u00bb de l\u2019onde sinuso\u00efdale. Elle est appel\u00e9e \u00able pic d\u2019amplitude\u00bb et repr\u00e9sente le point de d\u00e9placement maximal du  signal  magn\u00e9tique  par rapport \u00e0 l\u2019axe z\u00e9ro. En m\u00e9decine bio\u00e9lectromagn\u00e9tique, le pic de  l\u2019amplitude,  ou  intensit\u00e9 de l\u2019onde, est g\u00e9n\u00e9ralement mesur\u00e9 en microTesla (anciennement : Gauss).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Onde sinuso\u00efdale<\/h3>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/sinuswave-1.png\u00a0\u00bb title_text=\u00a0\u00bbsinuswave\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb scroll_horizontal_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|-2|0|2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Une onde magn\u00e9tique qui pr\u00e9sente des polarit\u00e9s altern\u00e9es (par exemple, des pics ou des cycles positifs et n\u00e9gatifs) est appel\u00e9e onde bipolaire. Les formes et les comportements des signaux magn\u00e9tiques peuvent \u00eatre manipul\u00e9s en modifiant les courants \u00e9lectriques qui les g\u00e9n\u00e8rent. Cela se fait g\u00e9n\u00e9ralement par le biais de commandes informatis\u00e9es. En combinant des cycles de pulsations magn\u00e9tiques g\u00e9n\u00e9r\u00e9es \u00e9lectriquement, on peut cr\u00e9er des \u00abtrains d\u2019impulsions\u00bb qui renforcent les effets biologiques du stimulus magn\u00e9tique. La composante la plus importante de la forme d\u2019onde est son temps de mont\u00e9e et son temps de descente. Selon Liboff, la valeur th\u00e9rapeutique d\u2019un signal puls\u00e9 donn\u00e9 d\u00e9pend fortement de la rapidit\u00e9 avec laquelle se produisent les temps de mont\u00e9e et de descente. Cette caract\u00e9ristique du signal ne peut \u00eatre sous-estim\u00e9e et constitue peut-\u00eatre le param\u00e8tre le plus important d\u2019un signal \u00e9lectromagn\u00e9tique. Le temps de chute abrupt repr\u00e9sente une valeur de tension de cr\u00eate \u00e9lev\u00e9e qui est responsable du d\u00e9placement des ions dans le corps. Un d\u00e9placement d\u2019ions plus important exerce un effet biologique plus fort. Plus efficaces qu\u2019une simple onde sinuso\u00efdale ou qu\u2019un aimant statique, les syst\u00e8mes iMRS Prime et Omnium1 g\u00e9n\u00e8rent des formes d\u2019ondes physiques tr\u00e8s complexes pour des r\u00e9sultats globaux favorables \u00e0 la sant\u00e9. La forme de signal dite en dents de scie et la forme d\u2019onde carr\u00e9e cr\u00e9ent des temps de mont\u00e9e et de descente beaucoup plus abrupts qu\u2019une simple onde sinuso\u00efdale, ce qui entra\u00eene un effet biologique plus important.<\/p>\n<p>Dans l\u2019ensemble, la forme d\u2019onde ou la forme du signal \u00e9lectromagn\u00e9tique est un \u00e9l\u00e9ment auquel il faut pr\u00eater une attention toute particuli\u00e8re. La forme d\u2019onde la plus efficace et la plus complexe pour obtenir des r\u00e9sultats holistiques favorables \u00e0 la sant\u00e9 est l\u2019onde en dents de scie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Ondes carr\u00e9es<br \/>\n<\/h3>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/squarewave-1.png\u00a0\u00bb title_text=\u00a0\u00bbsquarewave\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb scroll_horizontal_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|2|0|-2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Onde en dents de scie<\/h3>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/tripple_sawtooth-1.png\u00a0\u00bb title_text=\u00a0\u00bbtripple_sawtooth\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb scroll_horizontal_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|-2|0|2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]La preuve clinique de la forme d\u2019onde en dents de scie a \u00e9t\u00e9 publi\u00e9e pour la premi\u00e8re fois par le chercheur Bassett en 1974. Le Dr Bassett a observ\u00e9 que les variations du signal \u00e9lectromagn\u00e9tique induisent un courant \u00e9lectrique dans le tissu trait\u00e9. Le courant maximal pouvait \u00eatre mesur\u00e9 lorsque le signal appliqu\u00e9 passait brusquement de sa valeur maximale \u00e0 sa valeur minimale (temps de chute). Cette induction \u00abpi\u00e9zo\u00e9lectrique\u00bb au sein des structures osseuses acc\u00e9l\u00e8re la gu\u00e9rison des os. Gr\u00e2ce aux travaux de Bassett, cette forme d\u2019onde a \u00e9t\u00e9 approuv\u00e9e par la FDA aux \u00c9tats-Unis pour 1979 le traitement des fractures non consolid\u00e9es et pour faciliter les op\u00e9rations de fusion vert\u00e9brale.<\/p>\n<p>Les syst\u00e8mes iMRS Prime et Omnium1 sont tous deux \u00e9quip\u00e9s d\u2019un applicateur de matelas pour le corps entier. La forme du signal d\u00e9livr\u00e9 par la natte est une forme d\u2019onde en triple dents de scie. Cette forme d\u2019onde est un composite d\u2019un grand nombre d\u2019ondes harmonieuses et non sinuso\u00efdales dans la gamme des basses fr\u00e9quences. L\u2019impulsion en dents de scie de l\u2019iMRS Prime et de l\u2019applicateur du matelas pour le corps entier Omnium1 fournit  une  gamme  de fr\u00e9quences porteuses comprise entre 0,5 et 15 HZ, ce qui correspond \u00e0 100 % \u00e0 la \u00abfen\u00eatre biologique\u00bb.<\/p>\n<p>Contrairement aux simples ondes sinuso\u00efdales ou aux aimants statiques port\u00e9s par l\u2019ext\u00e9rieur, le signal en dents de scie change continuellement, produisant une induction constante de l\u2019\u00e9lectromagn\u00e9tisme dans les tissus du corps, maximisant le d\u00e9placement des ions et emp\u00eachant la fatigue de la membrane cellulaire. Cela signifie que la membrane cellulaire reste sensible aux signaux, ce qui renforce et optimise les effets b\u00e9n\u00e9fiques de la stimulation \u00e9lectromagn\u00e9tique. La recherche a montr\u00e9 que la forme d\u2019onde porteuse complexe \u00e0 triple dents de scie, utilis\u00e9e par l\u2019iMRS Prime et les matelas pour le corps entier Omnium1, fournit la plus haute probabilit\u00e9 de r\u00e9sonance de la stimulation \u00e9lectromagn\u00e9tique dans les tissus vivants et donc des avantages sup\u00e9rieurs en mati\u00e8re de sant\u00e9 et de bien-\u00eatre.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbfield_intensity\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Intensit\u00e9 du champ<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]L\u2019intensit\u00e9 du champ (\u00e9galement appel\u00e9e amplitude ou densit\u00e9 de flux) est une description quantitative d\u2019un champ \u00e9lectromagn\u00e9tique qui d\u00e9pend du flux et de la direction du courant. Elle a re\u00e7u l\u2019unit\u00e9 Tesla (T), d\u2019apr\u00e8s Nikola Tesla, un scientifique am\u00e9ricain d\u2019origine serbe qui est surtout connu pour ses nombreuses contributions r\u00e9volutionnaires dans le domaine de l\u2019\u00e9lectricit\u00e9 et du magn\u00e9tisme \u00e0 la fin du XIXe si\u00e8cle et au d\u00e9but du XXe si\u00e8cle. Le \u00abGauss\u00bb est une unit\u00e9 plus ancienne de densit\u00e9 de flux, qui est encore utilis\u00e9e comme norme dans plusieurs pays du monde (1 Gauss = 100 microTesla).<\/p>\n<p>Les facteurs d\u00e9terminants de l\u2019intensit\u00e9 du champ (amplitude) sont la longueur du fil de la bobine magn\u00e9tique, son diam\u00e8tre, le nombre de tours (ou \u00abenroulements\u00bb) de la bobine et l\u2019intensit\u00e9 du courant \u00e9lectrique (Amp\u00e8re) appliqu\u00e9 \u00e0 la bobine. Avec la constante d\u2019induction et la r\u00e9sistance physique sp\u00e9cifique du mat\u00e9riau, on peut calculer l\u2019intensit\u00e9 du champ (ou densit\u00e9 de flux) d\u2019un champ \u00e9lectromagn\u00e9tique.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/magnetfeld_erde.png\u00a0\u00bb alt=\u00a0\u00bbPEMF\u00a0\u00bb title_text=\u00a0\u00bbmagnetfeld_erde\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb scroll_rotating_enable=\u00a0\u00bbon\u00a0\u00bb scroll_rotating=\u00a0\u00bb0|50|50|100|-10\u00b0|0|10\u00b0\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Les syst\u00e8mes de diagnostic tels que l\u2019imagerie par r\u00e9sonance magn\u00e9tique (IRM) utilisent des intensit\u00e9s de champ de l\u2019ordre du Tesla (1,5 &#8211; 3T), tandis que les syst\u00e8mes iMRS Prime et Omnium1 exposent des intensit\u00e9s de champ extr\u00eamement faibles, de l\u2019ordre de trois microTesla. \u00c9tant donn\u00e9 que la cible de la signalisation est la membrane cellulaire, les intensit\u00e9s extr\u00eamement faibles sont tout \u00e0 fait appropri\u00e9es pour produire une r\u00e9ponse biologique hautement b\u00e9n\u00e9fique. Cette th\u00e8se est bas\u00e9e sur le principe de la \u00abfen\u00eatre biologique\u00bb, un concept d\u2019\u00e9tude d\u00e9velopp\u00e9, explor\u00e9 et publi\u00e9 par le Dr Ross Adey. Adey a d\u00e9couvert des plages sp\u00e9cifiques et \u00e9troites de fr\u00e9quences \u00e9lectromagn\u00e9tiques auxquelles le corps r\u00e9agit plus facilement. Ce principe peut \u00e9galement \u00eatre appliqu\u00e9 \u00e0 l\u2019intensit\u00e9 des champs : il existe une \u00abfen\u00eatre biologique\u00bb d\u2019intensit\u00e9s \u00e9lectromagn\u00e9tiques \u00e0 laquelle le corps humain r\u00e9agit le mieux et qui contribue \u00e0 la r\u00e9g\u00e9n\u00e9ration active des cellules et \u00e0 l\u2019am\u00e9lioration de l\u2019apport en oxyg\u00e8ne. Les recherches r\u00e9trospectives de Goodman et Blank ont prouv\u00e9 que les cellules humaines ext\u00e9riorisent plus facilement un g\u00e8ne pr\u00e9servant les cellules, la prot\u00e9ine de choc thermique 70 (hsp70), \u00e0 7-8 microTesla plut\u00f4t qu\u2019\u00e0 des intensit\u00e9s de champ plus fortes, sup\u00e9rieures \u00e0 70-100 microTesla.<\/p>\n<p>\u00abL\u2019esprit\u00bb natif d\u2019une cellule humaine, du point de vue \u00e9lectromagn\u00e9tique, r\u00e9agit plut\u00f4t sur un \u00abmurmure\u00bb subtil et doux.<\/p>\n<p>Les syst\u00e8mes de pointe iMRS Prime et Omnium1 sont \u00e9quip\u00e9s de ce \u00ablangage\u00bb natif et utilisent des intensit\u00e9s de champ extr\u00eamement faibles qui communiquent le plus efficacement possible avec la membrane cellulaire. Le r\u00e9sultat est le meilleur effet holistique possible sur la sant\u00e9 de toutes les cellules du corps.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbfrequency\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Fr\u00e9quence<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]De m\u00eame que nos cellules peuvent \u00eatre stimul\u00e9es par des produits chimiques (par exemple, des nutriments ou des m\u00e9dicaments) afin d\u2019ex\u00e9cuter des fonctions nouvelles et diff\u00e9rentes, elles peuvent \u00e9galement \u00eatre stimul\u00e9es \u00e9nerg\u00e9tiquement par des ondes \u00e9lectromagn\u00e9tiques. En fait, certaines fonctions cellulaires tr\u00e8s souhaitables sont stimul\u00e9es plus fortement par l\u2019\u00e9nergie que par la chimie. La largeur de bande saine des fr\u00e9quences \u00e9lectromagn\u00e9tiques est scientifiquement prouv\u00e9e. Ces plages de fr\u00e9quences sont appel\u00e9es \u00abfen\u00eatres biologiques\u00bb. Tant que la fr\u00e9quence d\u00e9livr\u00e9e se situe dans cette fen\u00eatre, elle est b\u00e9n\u00e9fique pour la cellule en termes d\u2019absorption de nutriments, d\u2019\u00e9limination des d\u00e9chets du m\u00e9tabolisme et de fonction cellulaire globale. C\u2019est pr\u00e9cis\u00e9ment ce que font les syst\u00e8mes iMRS Prime et Omnium1 : ils d\u00e9livrent les mod\u00e8les de fr\u00e9quence corrects dans les fen\u00eatres biologiques de la sant\u00e9 !<\/p>\n<p>Une analogie serait les fr\u00e9quences acoustiques. Certains sons sont trop forts pour \u00eatre appr\u00e9ci\u00e9s, d\u2019autres sont trop faibles pour \u00eatre entendus. Il y a une petite \u00abfen\u00eatre\u00bb de volume \u00e0 l\u2019int\u00e9rieur, qui cr\u00e9e une exp\u00e9rience auditive agr\u00e9able et m\u00eame une exp\u00e9rience auditive saine. Le m\u00eame principe s\u2019applique \u00e0 l\u2019\u00e9lectromagn\u00e9tisme. Il existe des fr\u00e9quences \u00e9lectromagn\u00e9tiques agr\u00e9ables et saines, d\u2019autres qui sont trop faibles pour \u00eatre assimil\u00e9es ou per\u00e7ues par le corps, et d\u2019autres qui sont si \u00abfortes\u00bb que les cellules subissent un impact n\u00e9gatif de ces signaux. Ces signaux nocifs et nuisibles sont appel\u00e9s \u00ab\u00e9lectrosmog\u00bb.<br \/>\nLes applicateurs iMRS Prime et Omnium1 pour le corps entier utilisent des 3 paires de bobines en cuivre massif non isol\u00e9es, avec des enroulements plus ou moins nombreux, pour simuler les fr\u00e9quences et les intensit\u00e9s \u00e9lectromagn\u00e9tiques du champ magn\u00e9tique terrestre. La nature nous apprend que ces fr\u00e9quences sont en parfaite harmonie avec la sant\u00e9 et le bien-\u00eatre. L\u2019utilisation quotidienne d\u2019un applicateur pour tout le corps favorise l\u2019\u00e9limination du stress et des tensions tout en encourageant un meilleur apport en oxyg\u00e8ne, en augmentant la circulation et en am\u00e9liorant le fonctionnement de votre corps au niveau cellulaire.<\/p>\n<p>Le taux de variation d\u2019une onde est sa \u00abfr\u00e9quence\u00bb. Les ondes ondulent d\u2019un pic \u00e0 un creux puis \u00e0 un pic. Le temps \u00e9coul\u00e9 entre un pic et le pic suivant est un cycle. Un cycle englobe un pic positif (au- dessus de la ligne) et un pic n\u00e9gatif. L\u2019unit\u00e9 de fr\u00e9quence la plus \u00e9l\u00e9mentaire est un cycle par seconde. Un cycle par seconde (cps) est \u00e9galement appel\u00e9 \u00abhertz\u00bb, en l\u2019honneur du physicien allemand du XIXe si\u00e8cle Heinrich Hertz, dont la d\u00e9couverte des ondes \u00e9lectromagn\u00e9tiques a conduit au d\u00e9veloppement de la radio. Une fr\u00e9quence de 25 Hertz (Hz) repr\u00e9sente 25 cycles par seconde. Le taux de fr\u00e9quence est mesur\u00e9 d\u2019un pic au pic suivant. L\u2019application d\u2019une onde sinuso\u00efdale est un mode simple par lequel l\u2019\u00e9nergie est transf\u00e9r\u00e9e vers un milieu (tel que le corps) ; plus le nombre de cycles par seconde est \u00e9lev\u00e9, plus le transfert d\u2019\u00e9nergie par seconde est important. Nous sommes plut\u00f4t conscients de l\u2019\u00e9nergie lumineuse et comprenons les ondes de lumi\u00e8re (photons). Cependant, le spectre de la lumi\u00e8re visible ne repr\u00e9sente qu\u2019une toute petite partie du spectre \u00e9lectromagn\u00e9tique.<\/p>\n<p>De m\u00eame, le son audible est une petite partie du spectre des fr\u00e9quences sonores (acoustique), et l\u2019oreille humaine ne peut d\u00e9tecter et r\u00e9pondre qu\u2019\u00e0 une infime partie des fr\u00e9quences qui se trouvent dans ce spectre. En ce qui concerne le transfert des signaux bio\u00e9lectromagn\u00e9tiques, la r\u00e8gle g\u00e9n\u00e9rale suivante s\u2019applique : Plus la fr\u00e9quence est \u00e9lev\u00e9e, plus l\u2019\u00e9nergie d\u00e9livr\u00e9e au corps est importante. Mais en comprenant le principe de la \u00abfen\u00eatre biologique\u00bb d\u2019Adey, nous savons que, tout comme la lumi\u00e8re et le son, le corps humain n\u2019est capable de r\u00e9agir de mani\u00e8re b\u00e9n\u00e9fique et saine qu\u2019\u00e0 une petite plage du spectre des fr\u00e9quences \u00e9lectromagn\u00e9tiques (effet de coh\u00e9rence).[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/frequencies.png\u00a0\u00bb title_text=\u00a0\u00bbfrequencies\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb scroll_horizontal_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_horizontal_motion=\u00a0\u00bb0|50|50|100|1|0|-1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]De nombreux fabricants de syst\u00e8mes CEMP \u00e0 usage domestique se vantent de cette puissance plus \u00e9lev\u00e9e et de ses avantages suppos\u00e9s, fid\u00e8les \u00e0 la devise : \u00abPlus on est de fous, plus on rit\u00bb. Chez Swissbionic Solutions, nous comprenons cependant que la m\u00e9decine \u00e9nerg\u00e9tique appliqu\u00e9e cliniquement ne fonctionne pas n\u00e9cessairement de cette fa\u00e7on. Les fr\u00e9quences naturelles dans les fen\u00eatres biologiques prouv\u00e9es sont les plus efficaces pour soutenir une sant\u00e9 et un bien-\u00eatre dynamiques &#8211; en substance : \u00abMoins, c\u2019est plus\u00bb ! Dans la th\u00e9rapie CEMP, les cycles sont appel\u00e9s impulsions. Ainsi, les cycles par seconde sont compris pour signifier des impulsions par seconde. Une fr\u00e9quence \u00e9lectromagn\u00e9tique de 25Hz est donc compos\u00e9e de 25 impulsions par seconde. Le corps humain contient de nombreuses fr\u00e9quences naturelles. Parmi elles, on trouve les battements du c\u0153ur, le flux du liquide c\u00e9phalo-rachidien, le rythme respiratoire et les ondes \u00e9lectromagn\u00e9tiques du cerveau. John Zimmerman, ancien docteur de l\u2019universit\u00e9 du Colorado, a constat\u00e9 que le toucher th\u00e9rapeutique de la main d\u2019un praticien \u00e9met une fr\u00e9quence \u00e9lectromagn\u00e9tique moyenne comprise entre 7 et 8 Hz lorsque le praticien est activement engag\u00e9 dans l\u2019application du toucher th\u00e9rapeutique. Il est int\u00e9ressant de noter que les r\u00e9sonances de Schumann produites dans l\u2019ionosph\u00e8re terrestre sont scientifiquement \u00e9valu\u00e9es \u00e0 7,83Hz. Le champ magn\u00e9tique terrestre a \u00e9t\u00e9 scientifiquement calcul\u00e9 \u00e0 une gamme comprise entre 11,75 et 11,79 Hz (Piontzik). Les ondes alpha du cerveau semblent \u00eatre tr\u00e8s similaires, voire virtuellement identiques aux fr\u00e9quences naturelles de Schumann.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbschumann_resonance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>R\u00e9sonance de Schumann<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]En 1954, Schumann et K\u00f6nig ont fait \u00e9tat de leur d\u00e9couverte de pulsations \u00e9lectromagn\u00e9tiques naturelles sur la Terre. Les r\u00e9sonances de Schumann sont des ondes naturelles excit\u00e9es par les \u00e9clairs dans la cavit\u00e9 situ\u00e9e entre la surface de la Terre et l\u2019ionosph\u00e8re. En fait, les \u00e9clairs pompent de l\u2019\u00e9nergie dans la cavit\u00e9 de l\u2019atmosph\u00e8re terrestre et la font vibrer ou r\u00e9sonner \u00e0 des fr\u00e9quences extr\u00eamement basses. Les ondes \u00e9lectromagn\u00e9tiques cr\u00e9\u00e9es par les \u00e9clairs voyagent autour de la Terre \u00e0 la vitesse de la lumi\u00e8re, se refl\u00e9tant de l\u2019ionosph\u00e8re \u00e0 la Terre et inversement de fa\u00e7on cyclique. Ces ondes font le tour du globe en moyenne 7,83 fois par seconde. Comme indiqu\u00e9 plus haut, cette fr\u00e9quence est en corr\u00e9lation avec la fr\u00e9quence moyenne des ondes c\u00e9r\u00e9brales alpha chez l\u2019\u00eatre humain. La fr\u00e9quence porteuse du champ magn\u00e9tique terrestre est scientifiquement document\u00e9e et \u00e9valu\u00e9e \u00e0 &#8211; 11.75Hz &#8211; 11.79Hz (Piontzik).[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; prev_background_color=\u00a0\u00bb#000000&Prime; next_background_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/schumann3.jpg\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb parallax_method=\u00a0\u00bboff\u00a0\u00bb top_divider_style=\u00a0\u00bbwave2&Prime; bottom_divider_style=\u00a0\u00bbwave2&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb50vh\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La fr\u00e9quence porteuse des r\u00e9sonances de Schumann (\u00abfr\u00e9quence tonique\u00bb) est exactement \u00e9gale \u00e0 7.83Hz. Une harmonique est d\u00e9finie comme une hauteur sup\u00e9rieure de la fr\u00e9quence de base dans un syst\u00e8me vibratoire. Ceux qui chantent ou jouent de la guitare sont familiers avec la cr\u00e9ation d\u2019harmoniques &#8211; des fr\u00e9quences sonores qui sont souvent cr\u00e9\u00e9es en superposant une fr\u00e9quence fondamentale \u00e0 une autre. D\u2019autres hauteurs naturelles se produisent \u00e0 des intervalles de 6,5 Hz en raison de la g\u00e9om\u00e9trie spatiale de la Terre. Des harmoniques suppl\u00e9mentaires peuvent \u00eatre d\u00e9tect\u00e9es dans le bruit de fond radio\u00e9lectrique du champ \u00e9nerg\u00e9tique de la Terre sous la forme de hauteurs distinctes entre 14 et 35 Hz. En outre, ces harmoniques semblent \u00eatre essentielles pour notre corps.<\/p>\n<p>Si notre corps est s\u00e9par\u00e9 ou bloqu\u00e9 de l\u2019exposition naturelle \u00e0 ces vibrations (par exemple, en raison de la vie et du travail dans des b\u00e2timents construits avec du b\u00e9ton, de l\u2019acier et des alliages m\u00e9talliques, de la conduite de voitures sur des routes goudronn\u00e9es, et de l\u2019\u00e9lectropollution par les radiations \u00e0 ultra-haute fr\u00e9quence des t\u00e9l\u00e9phones cellulaires, des fours \u00e0 micro-ondes, des t\u00e9l\u00e9phones domestiques sans fil, des r\u00e9seaux WIFI, des signaux radar\/ satellites, etc. Les fluctuations enregistr\u00e9es dans les r\u00e9sonances Schumann de la Terre ont \u00e9t\u00e9 fortement corr\u00e9l\u00e9es aux crises cardiaques, aux accidents de voiture et \u00e0 une augmentation g\u00e9n\u00e9rale des taux de mortalit\u00e9 (Beck 1992).<\/p>\n<p>Il existe une \u00e9norme gamme de fr\u00e9quences \u00e9lectromagn\u00e9tiques d\u00e9j\u00e0 utilis\u00e9es ou dont l\u2019utilisation est propos\u00e9e dans le domaine de la sant\u00e9. L\u2019accent est mis sur l\u2019application cibl\u00e9e avec des indications d\u00e9finies (comme la stimulation magn\u00e9tique transcr\u00e2nienne r\u00e9p\u00e9titive (SMTr) pour la d\u00e9pression). Les fr\u00e9quences utilis\u00e9es vont de la gamme des fr\u00e9quences extr\u00eamement basses (ELF) de 3 \u00e0 300 Hz \u00e0 la gamme sup\u00e9rieure de 50 milliards de Hz (50 GHz). Pour les applications m\u00e9dicales de CEMP \u00e0 domicile et pour des raisons de s\u00e9curit\u00e9, il est recommand\u00e9 de choisir des appareils m\u00e9dicaux certifi\u00e9s tels que l\u2019iMRS Prime et l\u2019Omnium1, conformes \u00e0 la derni\u00e8re norme MDR (2017\/745), d\u00e9livrant des fr\u00e9quences dans la gamme ELF (Fr\u00e9quence extr\u00eamement basse). Les deux syst\u00e8mes g\u00e9n\u00e8rent des formes d\u2019onde (dents de scie et ondes carr\u00e9es) qui, en raison de leurs propri\u00e9t\u00e9s physiques, d\u00e9livrent non seulement de grandes quantit\u00e9s de fr\u00e9quences uniques et de leurs harmoniques, mais aussi les temps de mont\u00e9e et de descente rapides n\u00e9cessaires pour initier et maintenir les effets de r\u00e9sonance souhait\u00e9s avec les cellules du corps.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbresonance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>R\u00e9sonance<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]La r\u00e9sonance est un principe qui a \u00e9t\u00e9 d\u00e9couvert par Galileo Galilei en 1602 alors qu\u2019il \u00e9tudiait les pendules. La r\u00e9sonance est la tendance d\u2019un syst\u00e8me \u00e0 osciller avec une amplitude maximale \u00e0 certaines fr\u00e9quences.<\/p>\n<p>Un exemple courant de r\u00e9sonance est la balan\u00e7oire d\u2019une aire de jeux, qui agit comme un pendule. Si vous poussez un enfant sur une balan\u00e7oire au rythme de l\u2019intervalle naturel de la balan\u00e7oire (sa fr\u00e9quence de r\u00e9sonance), la balan\u00e7oire montera de plus en plus haut (jusqu\u2019\u00e0 son amplitude maximale). En appliquant une force de pouss\u00e9e \u00e0 tout autre moment interf\u00e9rera avec la fr\u00e9quence de r\u00e9sonance ou l\u2019amortira et l\u2019amplitude de la balan\u00e7oire sera r\u00e9duite, perturb\u00e9e ou compl\u00e8tement arr\u00eat\u00e9e.<br \/>\nL\u2019\u00e9nergie (pouss\u00e9e externe) absorb\u00e9e par la balan\u00e7oire est maximis\u00e9e lorsqu\u2019elle est synchronis\u00e9e (ou \u00aben r\u00e9sonance\u00bb) avec les propres oscillations de la balan\u00e7oire.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/resonance.jpg\u00a0\u00bb title_text=\u00a0\u00bbresonance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb250ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Chaque cellule du corps humain vibre ou oscille. On peut l\u2019observer visuellement sur des s\u00e9quences vid\u00e9o \u00e0 fort grossissement lorsque les globules rouges se d\u00e9placent dans les vaisseaux ou que les macrophages chassent les bact\u00e9ries. Les champs \u00e9lectromagn\u00e9tiques puls\u00e9s avec un spectre de fr\u00e9quences appropri\u00e9 sont capables de produire une r\u00e9sonance cellulaire = vibration \u00e0 amplitude maximale. Ils d\u00e9clenchent les fr\u00e9quences porteuses respectives des r\u00e9cepteurs (neuropeptides) dans le but de stimuler une vari\u00e9t\u00e9 de fonctions autour et \u00e0 l\u2019int\u00e9rieur de chaque cellule. Le corps humain est compos\u00e9 d\u2019environ 75 trillions de cellules (en fonction de la taille et du poids) et chaque membrane cellulaire contient plus d\u2019un million de r\u00e9cepteurs neuropeptidiques. Un champ \u00e9lectromagn\u00e9tique puls\u00e9 pr\u00e9cis\u00e9ment d\u00e9fini \u00e0 l\u2019int\u00e9rieur de la fen\u00eatre biologique signale simultan\u00e9ment tous ces r\u00e9cepteurs \u00e0 la vitesse de la lumi\u00e8re et les incite \u00e0 entrer en r\u00e9sonance avec les vibrations appliqu\u00e9es. C\u2019est la propri\u00e9t\u00e9 essentielle de la PEMF.<\/p>\n<p>Les profonds effets b\u00e9n\u00e9fiques des CEMP sur la physiologie humaine sont dus \u00e0 l\u2019am\u00e9lioration de la communication et de l\u2019interaction inter et intracellulaire produite par l\u2019induction de la r\u00e9sonance dans le corps. Jusqu\u2019\u00e0 aujourd\u2019hui, il n\u2019est pas scientifiquement prouv\u00e9 que les fr\u00e9quences situ\u00e9es en dehors de la fen\u00eatre biologique soient capables de cr\u00e9er des effets de r\u00e9sonance sur les structures cellulaires.<br \/>\nPlus la fr\u00e9quence est \u00e9lev\u00e9e, plus il est difficile de mesurer l\u2019effet sur la cellule. Il est important de noter que cela s\u2019applique aux fr\u00e9quences \u00abnon naturelles\u00bb dans la gamme des KHz et des MHz expos\u00e9es par les t\u00e9l\u00e9phones domestiques sans fil, les smartphones, les routeurs WIFI et de nombreux appareils \u00e9lectriques domestiques courants. La derni\u00e8re g\u00e9n\u00e9ration de syst\u00e8mes CEMP certifi\u00e9s m\u00e9dicalement et les plus efficaces, l\u2019iMRS Prime ou l\u2019Omnium1, ciblent la gamme de fr\u00e9quences extr\u00eamement basses correspondant aux vibrations oscillatoires toniques connues des cellules du corps. Ils repr\u00e9sentent la r\u00e9f\u00e9rence absolue de l\u2019utilisation d\u2019un mod\u00e8le de r\u00e9sonance stochastique informatis\u00e9 avanc\u00e9 pour obtenir une r\u00e9sonance cellulaire maximale.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbbiological_window\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Fen\u00eatre biologique<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/biological_window.jpg\u00a0\u00bb title_text=\u00a0\u00bbbiological_window\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb250ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Le Dr William Ross Adey, professeur d\u2019anatomie et de physiologie n\u00e9 en Australie et travaillant \u00e0 la facult\u00e9 de m\u00e9decine de l\u2019UCLA, a invent\u00e9 le terme de \u00abfen\u00eatre biologique\u00bb (Bawin et Adey 1976). (Bawin et Adey 1976) Adey a mesur\u00e9 la production de calcium des cellules du cerveau chez les lapins pour d\u00e9montrer que cet effet ne pouvait \u00eatre d\u00e9clench\u00e9 qu\u2019en utilisant des intensit\u00e9s de champ magn\u00e9tique tr\u00e8s faibles et une basse fr\u00e9quence sp\u00e9cifique (16 Hz). Depuis la d\u00e9couverte initiale du Dr Adey, la litt\u00e9rature sur la m\u00e9decine \u00e9nerg\u00e9tique a montr\u00e9 un fort consensus scientifique sur l\u2019importance des fen\u00eatres biologiques.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Une fen\u00eatre biologique est une gamme ou un spectre d\u2019\u00e9nergies \u00e9lectromagn\u00e9tiques qui sont facilement accept\u00e9es par le corps et converties en r\u00e9ponses physiologiques positives. Les signaux qui se situent en dehors de la fen\u00eatre biologique ont peu ou pas d\u2019effet, voire dans certains cas un effet n\u00e9gatif ou toxique. Par analogie, les fr\u00e9quences audibles peuvent \u00eatre agr\u00e9ables (par exemple, une symphonie) ou destructives (par exemple, le son d\u2019une explosion peut d\u00e9truire d\u00e9finitivement l\u2019ou\u00efe). La recherche a prouv\u00e9 que les tissus vivants d\u00e9tectent, absorbent et utilisent facilement les signaux \u00e9lectromagn\u00e9tiques dans certaines plages de fr\u00e9quences et ignorent compl\u00e8tement les autres fr\u00e9quences naturellement pr\u00e9sentes dans le spectre des fr\u00e9quences.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bborgan_clock\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Horloge biorythmique<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Les applicateurs corps entier des syst\u00e8mes iMRS Prime et Omnium1 utilisent des mod\u00e8les de fr\u00e9quence pr\u00e9programm\u00e9s qui varient en fonction du moment de la journ\u00e9e  o\u00f9 l\u2019appareil est utilis\u00e9. Cette variation temporelle de la fr\u00e9quence est due aux rythmes circadiens naturellement observ\u00e9s. Ce  ph\u00e9nom\u00e8ne  est  entre-temps  scientifiquement prouv\u00e9 et a \u00e9t\u00e9 r\u00e9compens\u00e9 par le prix Nobel de m\u00e9decine 2017 (Hall, Rosbash et Young : Discoveries  of Molecular Mechanisms Controlling the Circadian Rhythm). Selon la m\u00e9decine traditionnelle chinoise (et d\u2019autres anciennes traditions de gu\u00e9rison en Asie), l\u2019\u00e9nergie vitale circule dans les douze organes et accomplit un cycle toutes  les vingt-quatre heures. L\u2019horloge chinoise des organes montre le flux circadien de l\u2019\u00e9nergie vitale (Qi &#8211; prononc\u00e9 \u00abChi\u00bb) \u00e0 travers les diff\u00e9rents syst\u00e8mes d\u2019organes en fonction de l\u2019heure de la journ\u00e9e. Chaque organe dispose d\u2019une \u00e9nergie maximale pendant deux heures. L\u2019organe a une \u00e9nergie minimale (ou le plus faible flux de Qi) 12 heures plus tard.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<table class=\"table_organ_clock\">\n<tbody>\n<tr>\n<th style=\"width: 33.3333%;\">HEURE<\/th>\n<th style=\"width: 33.3333%;\">ENERGIE MAXIMALE<\/th>\n<th style=\"width: 33.3333%;\">ORGUE\/M\u00c9RIDIEN<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">3h \u00e0 5h<\/td>\n<td style=\"width: 33.3333%;\">4h<\/td>\n<td style=\"width: 33.3333%;\">POUMONS<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">5h \u00e0 7h<\/td>\n<td style=\"width: 33.3333%;\">6h<\/td>\n<td style=\"width: 33.3333%;\">GROS INTESTIN<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">7h \u00e0 9h<\/td>\n<td style=\"width: 33.3333%;\">8h<\/td>\n<td style=\"width: 33.3333%;\">ESTOMAC<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">9h \u00e0 11h<\/td>\n<td style=\"width: 33.3333%;\">10h<\/td>\n<td style=\"width: 33.3333%;\">RATE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">11h \u00e0 13h<\/td>\n<td style=\"width: 33.3333%;\">12h<\/td>\n<td style=\"width: 33.3333%;\">COEUR<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">13h \u00e0 15h<\/td>\n<td style=\"width: 33.3333%;\">14h<\/td>\n<td style=\"width: 33.3333%;\">PETIT INTESTIN<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">15h \u00e0 17h<\/td>\n<td style=\"width: 33.3333%;\">16h<\/td>\n<td style=\"width: 33.3333%;\">VESSIE URINAIRE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">17h \u00e0 19h<\/td>\n<td style=\"width: 33.3333%;\">18h<\/td>\n<td style=\"width: 33.3333%;\">KIDNEY<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">19h \u00e0 21h<\/td>\n<td style=\"width: 33.3333%;\">20h<\/td>\n<td style=\"width: 33.3333%;\">PERICARD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">21h \u00e0 23h<\/td>\n<td style=\"width: 33.3333%;\">22h<\/td>\n<td style=\"width: 33.3333%;\">TRIPLE R\u00c9CHAUFFEUR<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">23h \u00e0 1h<\/td>\n<td style=\"width: 33.3333%;\">0 h<\/td>\n<td style=\"width: 33.3333%;\">VESICULE BILAIRE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">1h \u00e0 3h<\/td>\n<td style=\"width: 33.3333%;\">2 h<\/td>\n<td style=\"width: 33.3333%;\">FOIE<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; background_image=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/organuhr_french-1.png\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb parallax_method=\u00a0\u00bboff\u00a0\u00bb height=\u00a0\u00bb100vh\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22background_color%22%93}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb50vh\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Le graphique ci-dessus montre que le flux d\u2019\u00e9nergie maximal \u00e0 travers le foie se situe \u00e0 2 heures du matin. Par cons\u00e9quent, le flux d\u2019\u00e9nergie correspondant le plus faible du foie est \u00e0 14 heures. L\u2019iMRS d\u00e9livre des paquets d\u2019\u00e9nergie qui sont cens\u00e9s \u00e9quilibrer la r\u00e9sonance cellulaire de tous les organes et syst\u00e8mes corporels simultan\u00e9ment en variant les fr\u00e9quences \u00e0 travers 4 intervalles pr\u00e9programm\u00e9s :<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb5 h &#8211; 10 h \u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe031;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb10 h &#8211; 15 h\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe031;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb250ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb15 h &#8211; 20 h\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe031;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb500ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb20 h &#8211; 5 h\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe031;||divi||400&Prime; icon_color=\u00a0\u00bbgcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_delay=\u00a0\u00bb750ms\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Les paquets d\u2019impulsions d\u00e9livr\u00e9s par l\u2019applicateur matelas du corps entier de l\u2019iMRS Prime ou de l\u2019Omnium1 utilisent la forme complexe et tr\u00e8s efficace du signal en triple dents  de scie et sont des  composites  d\u2019un  grand  nombre  de  fr\u00e9quences  \u00e9lectromagn\u00e9tiques uniques dans la gamme des fr\u00e9quences extr\u00eamement basses (ELF). Cela permet de transf\u00e9rer un maximum de fr\u00e9quences uniques et leurs  harmoniques  pendant  de courtes dur\u00e9es d\u2019application (8-24 min.). Toutes les 2 minutes, pendant cette signalisation, la polarit\u00e9 est invers\u00e9e afin d\u2019\u00e9viter la fatigue et l\u2019adaptation des cellules au signal. Ce concept est destin\u00e9 \u00e0 maximiser le succ\u00e8s th\u00e9rapeutique durable. <\/p>\n<p>Les applicateurs Pad et Spot, plus petits, sont capables d\u2019atteindre des intensit\u00e9s de champ plus \u00e9lev\u00e9es et sont tr\u00e8s simples \u00e0 utiliser pour une application externe sur le corps. Il n\u2019est pas n\u00e9cessaire de r\u00e9gler l\u2019horloge biologique pour ces applicateurs, car l\u2019application locale de CEMP vise \u00e0 traiter une indication isol\u00e9e (cicatrisation, gu\u00e9rison osseuse, augmentation p\u00e9riph\u00e9rique de la circulation sanguine, soulagement de la douleur). Une forme d\u2019onde rectangulaire sp\u00e9cifique (onde carr\u00e9e) est utilis\u00e9e pour obtenir les r\u00e9sultats les meilleurs et les plus rapides.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#A8343A\u00a0\u00bb top_divider_height=\u00a0\u00bb60px\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.swissbionic.com\/wp-content\/uploads\/brochure_pemf_fr.png\u00a0\u00bb title_text=\u00a0\u00bbbrochure_pemf_fr\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/backoffice.swissbionic.com\/documents\/flyer2025\/pemf_in_a_nutshell_fr_202503_a.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_align=\u00a0\u00bbleft\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bb\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>CEMP en bref<\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/backoffice.swissbionic.com\/documents\/flyer2025\/pemf_in_a_nutshell_fr_202503_a.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbT\u00e9l\u00e9charger ici\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#A8343A\u00a0\u00bb button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb3px\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb20%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CEMP champs \u00e9lectromagn\u00e9tiques puls\u00e9sUn champ \u00e9lectromagn\u00e9tique (\u00e9galement appel\u00e9 CEM ou champ EM) est une quantit\u00e9 physique produite par des objets charg\u00e9s \u00e9lectriquement. Les quatre param\u00e8tres cruciaux d\u00e9finissant la structure du signal expos\u00e9 sont les suivants :En th\u00e9orie, ces 4 composants doivent \u00eatre soigneusement dispos\u00e9s en \u00e9quilibre mutuel (coh\u00e9rence) et introduits dans le corps afin de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/pages\/232585"}],"collection":[{"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/comments?post=232585"}],"version-history":[{"count":3,"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/pages\/232585\/revisions"}],"predecessor-version":[{"id":236531,"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/pages\/232585\/revisions\/236531"}],"wp:attachment":[{"href":"https:\/\/julietilthealthcoaching.swissbionic.com\/fr\/wp-json\/wp\/v2\/media?parent=232585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}